{"id":1003897,"date":"2019-08-12T20:36:49","date_gmt":"2019-08-12T20:36:49","guid":{"rendered":"https:\/\/www.ibewcanada.ca\/?p=1003897"},"modified":"2019-08-20T19:48:23","modified_gmt":"2019-08-20T19:48:23","slug":"with-election-approaching-new-contract-secures-gains-for-federal-workers","status":"publish","type":"post","link":"https:\/\/www.ibewcanada.ca\/fr\/news\/with-election-approaching-new-contract-secures-gains-for-federal-workers\/","title":{"rendered":"\u00c0 l&#8217;approche de l&#8217;\u00e9lection, le nouveau contrat assure des gains pour le personnel de comp\u00e9tence f\u00e9d\u00e9rale"},"content":{"rendered":"<p><a href=\"https:\/\/www.ibewcanada.ca\/wp-content\/uploads\/2019\/08\/190718_Election.jpg\"><img decoding=\"async\" class=\"alignleft wp-image-1003900\" src=\"https:\/\/www.ibewcanada.ca\/wp-content\/uploads\/2019\/08\/190718_Election-300x120.jpg\" alt=\"\" width=\"340\" height=\"136\" srcset=\"https:\/\/www.ibewcanada.ca\/wp-content\/uploads\/2019\/08\/190718_Election-300x120.jpg 300w, https:\/\/www.ibewcanada.ca\/wp-content\/uploads\/2019\/08\/190718_Election-768x307.jpg 768w, https:\/\/www.ibewcanada.ca\/wp-content\/uploads\/2019\/08\/190718_Election-1024x410.jpg 1024w, https:\/\/www.ibewcanada.ca\/wp-content\/uploads\/2019\/08\/190718_Election.jpg 1260w\" sizes=\"(max-width: 340px) 100vw, 340px\" \/><\/a><\/p>\n<h5><\/h5>\n<h5><em>Cr\u00e9dit : Creative Commons\/par l&#8217;utilisateur Flickr Gerard Donnelly\u00a0<\/em><\/h5>\n<h5 id=\"tw-target-text\" class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Translation\"><em><span lang=\"fr\" tabindex=\"0\">L&#8217;Amundsen, un brise-glace et un navire de recherche de la Garde c\u00f4ti\u00e8re amarr\u00e9 \u00e0 Qu\u00e9bec, est l&#8217;un des nombreux lieux de travail tr\u00e8s diversifi\u00e9s parmi la gamme des plus de 1 000 technologues en \u00e9lectronique couverts par le nouvel accord avec le gouvernement canadien.<\/span><\/em><\/h5>\n<p>\u00c0 l&#8217;aube de l&#8217;\u00e9lection f\u00e9d\u00e9rale, le local 2228 situ\u00e9 \u00e0 Ottawa, Ontario a conclu une entente de principe avec le Conseil du Tr\u00e9sor pour les quatre prochaines ann\u00e9es, offrant ainsi une augmentation salariale de 8 pour cent \u00e0 plus de 1\u2009000 membres vis\u00e9s.<\/p>\n<p>Les membres couverts par cette convention collective sont des technologues de l&#8217;\u00e9lectronique qui travaillent au sein du gouvernement f\u00e9d\u00e9ral. Le personnel est r\u00e9parti \u00e0 travers 18 secteurs diff\u00e9rents, notamment la D\u00e9fense nationale, la Garde c\u00f4ti\u00e8re canadienne et Transports Canada. L&#8217;entente du local\u00a02228 passait au vote au moment de l&#8217;impression du journal <em>The Electrical Worker<\/em>.<\/p>\n<p>La convention collective permet, entre autres, aux membres d&#8217;avoir plus de cong\u00e9s parentaux, plus de cong\u00e9s de maternit\u00e9 et plus de cong\u00e9s pour les aides familiaux, et un cong\u00e9 a \u00e9t\u00e9 \u00e9tabli pour les membres qui font face aux cas de violence domestiques. Le g\u00e9rant d&#8217;affaires Paul Cameron se r\u00e9jouit particuli\u00e8rement du fait d&#8217;avoir conclu une entente avant l&#8217;ann\u00e9e o\u00f9 la pr\u00e9c\u00e9dente expire, ce qui permettra aux membres d&#8217;\u00eatre mieux pr\u00e9par\u00e9s pour leur avenir.<\/p>\n<p>\u00ab\u2009Nous avons entam\u00e9 nos n\u00e9gociations avec ce qui correspondait, \u00e0 notre avis, des propositions justes et claires,\u2009\u00bb dit Cameron. \u00ab\u2009Nous n&#8217;avons pas voulu compliquer les choses. On savait que les choses allaient bouger en raison de l&#8217;\u00e9lection f\u00e9d\u00e9rale imminente.\u2009\u00bb<\/p>\n<p>La session parlementaire a pris fin en juin et l&#8217;\u00e9lection f\u00e9d\u00e9rale sera tenue en octobre. Les leaders syndicaux de la FIOE exhortent les membres \u00e0 appuyer les candidates et les candidats favorables au mouvement ouvrier, y compris celles et ceux du Parti lib\u00e9ral d\u00e9j\u00e0 au pouvoir, qui \u00e9taient favorables \u00e0 un dialogue ouvert avec la FIOE ainsi qu&#8217;avec les autres syndicats canadiens.<\/p>\n<p>Avant l&#8217;arriv\u00e9e au pouvoir des lib\u00e9raux en 2015, le Parti conservateur s&#8217;est montr\u00e9 hostile envers les syndicats au cours des 10 derni\u00e8res ann\u00e9es, autant lorsqu&#8217;il a form\u00e9 le gouvernement que lorsqu&#8217;il a \u00e9t\u00e9 majoritaire. Cameron dit que ce changement paraissait durant les n\u00e9gociations. L&#8217;arriv\u00e9e \u00e0 une entente avec les lib\u00e9raux au pouvoir \u00e9tait plus facile, contrairement \u00e0 l&#8217;ancien gouvernement conservateur. Il y avait plus de flexibilit\u00e9 et plus d&#8217;ouverture \u00e0 l&#8217;\u00e9gard des propositions du local\u00a02228, et non avec la mentalit\u00e9 \u00ab\u2009c&#8217;est \u00e0 prendre ou \u00e0 laisser\u2009\u00bb, tel que v\u00e9cu dans les n\u00e9gociations pr\u00e9c\u00e9dentes.<\/p>\n<p>\u00ab\u2009G\u00e9n\u00e9ralement, au cours de ces 10 \u00e0 20 derni\u00e8res ann\u00e9es, les n\u00e9gociations jusqu&#8217;au moment de la ratification prenaient deux ans,\u2009\u00bb ajoute Cameron. \u00ab\u2009Lorsque les conservateurs \u00e9taient au pouvoir, on avait vraiment l&#8217;impression d&#8217;\u00eatre forc\u00e9 \u00e0 accepter l&#8217;accord sinon ils allaient l\u00e9gif\u00e9rer. L&#8217;\u00e9change n&#8217;\u00e9tait pas amical. Alors qu&#8217;avec les lib\u00e9raux au pouvoir, on avait plus le sentiment que c&#8217;\u00e9tait une collaboration.\u2009\u00bb<\/p>\n<p>\u00ab\u2009Il s&#8217;agit d&#8217;un gain par rapport \u00e0 ce que nous avions eu au dernier cycle de n\u00e9gociation. Avons-nous obtenu tout ce que nous voulions\u2009? Non. Mais nous avons estim\u00e9 que c&#8217;\u00e9tait une entente \u00e9quitable qui repr\u00e9sente la valeur et le travail de nos membres.\u2009\u00bb<\/p>\n<p>On s&#8217;attend \u00e0 ce que l&#8217;\u00e9lection f\u00e9d\u00e9rale soit extr\u00eamement serr\u00e9e. Le sondage \u00e9lectoral des bulletins de nouvelles <em>CBC<\/em> a donn\u00e9 au Parti conservateur 35 pour cent des chances pour former le gouvernement majoritaire et le Parti lib\u00e9ral\u00a029 pour cent des chances.<\/p>\n<p>\u00ab\u2009Paul et son \u00e9quipe de n\u00e9gociation ont fait preuve de leadership extraordinaire en concluant cette entente de mani\u00e8re \u00e9quitable pour leur membre, bien que plusieurs d&#8217;entre eux effectuent un travail tr\u00e8s important et rarement \u00e0 la vue du public,\u2009\u00bb mentionne Matt Wayland, le directeur canadien des relations gouvernementales.<\/p>\n<p>\u00ab\u2009Mais comme il a fait mention, en ayant un gouvernement au pouvoir qui respecte le processus de n\u00e9gociation collective et la valeur des fonctionnaires, ont rendu les n\u00e9gociations beaucoup plus productives. C&#8217;est une raison pour laquelle il faut appuyer les candidates et les candidats favorables aux travailleuses et travailleurs et ne pas oublier les gains que nous avons r\u00e9alis\u00e9s dans les quatre derni\u00e8res ann\u00e9es.\u2009\u00bb<\/p>\n<p>La convention collective avec la FIOE faisait partie des cinq nouveaux contrats conclus entre le Conseil du Tr\u00e9sor et les syndicats du secteur public, qui visent environ 30\u2009000 travailleuses et travailleurs.<\/p>\n<p>\u00ab\u2009Ceci est un autre exemple qui fait preuve de respect d\u00e9montr\u00e9 de fa\u00e7on constante par notre gouvernement \u00e0 nos fonctionnaires du Canada,\u2009\u00bb exprime Joyce Murray, la pr\u00e9sidente du Conseil du Tr\u00e9sor. \u00ab\u2009Nous restons d\u00e9termin\u00e9s \u00e0 n\u00e9gocier collectivement de bonne foi et esp\u00e9rons conclure des conventions collectives qui sont profitables pour les fonctionnaires et justes pour les contribuables canadiens.\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9dit : Creative Commons\/par l&#8217;utilisateur Flickr Gerard Donnelly\u00a0 L&#8217;Amundsen, un brise-glace et un navire de recherche de la Garde c\u00f4ti\u00e8re amarr\u00e9 \u00e0 Qu\u00e9bec, est l&#8217;un des nombreux lieux de travail tr\u00e8s diversifi\u00e9s parmi la gamme des plus de 1 000 technologues en \u00e9lectronique couverts par le nouvel accord avec le gouvernement canadien. \u00c0 l&#8217;aube de&#8230;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-1003897","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-uncategorized","7":"entry"},"translation":{"provider":"WPGlobus","version":"3.0.2","language":"fr","enabled_languages":["en","fr"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false}}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.ibewcanada.ca\/fr\/wp-json\/wp\/v2\/posts\/1003897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ibewcanada.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ibewcanada.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ibewcanada.ca\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ibewcanada.ca\/fr\/wp-json\/wp\/v2\/comments?post=1003897"}],"version-history":[{"count":0,"href":"https:\/\/www.ibewcanada.ca\/fr\/wp-json\/wp\/v2\/posts\/1003897\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.ibewcanada.ca\/fr\/wp-json\/wp\/v2\/media?parent=1003897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ibewcanada.ca\/fr\/wp-json\/wp\/v2\/categories?post=1003897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ibewcanada.ca\/fr\/wp-json\/wp\/v2\/tags?post=1003897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}