{"id":1003804,"date":"2019-07-10T12:26:39","date_gmt":"2019-07-10T12:26:39","guid":{"rendered":"https:\/\/www.ibewcanada.ca\/?p=1003804"},"modified":"2019-07-10T16:13:33","modified_gmt":"2019-07-10T16:13:33","slug":"national-lineworker-appreciation-day","status":"publish","type":"post","link":"https:\/\/www.ibewcanada.ca\/fr\/news\/national-lineworker-appreciation-day\/","title":{"rendered":"Journ\u00e9e nationale de reconnaissance des monteurs de lignes"},"content":{"rendered":"<p>La FIOE Canada s\u2019est jointe \u00e0 l\u2019Association canadienne de l\u2019\u00e9lectricit\u00e9 (AC\u00c9) le 2 octobre 2018 pour lancer une campagne nationale qui a pour but de r\u00e9clamer une loi f\u00e9d\u00e9rale pour d\u00e9signer le 10 juillet comme la Journ\u00e9e nationale de reconnaissance des monteurs de lignes. Le 10 juillet est une journ\u00e9e tr\u00e8s importante pour la FIOE; notre fondateur Henry Miller, et lui-m\u00eame monteur de lignes, est d\u00e9c\u00e9d\u00e9 le 10 juillet 1896 en raison d\u2019un accident au travail. Les temps violents d\u2019un bout \u00e0 l\u2019autre du pays incluant le Grand Nord ont soulign\u00e9 encore plus l\u2019importance du travail des monteurs de lignes qui assurent la distribution d\u2019\u00e9nergie continue aux Canadiens. Cette Journ\u00e9e de reconnaissance est notre fa\u00e7on de remercier tous les travailleurs qui participent \u00e0 restaurer l\u2019\u00e9lectricit\u00e9 de mani\u00e8re efficace et en s\u00fbret\u00e9 partout au pays.<\/p>\n<p>Nous avons bien h\u00e2te de voir de quelle fa\u00e7on vous avez c\u00e9l\u00e9br\u00e9 la Journ\u00e9e nationale de reconnaissance des monteurs de lignes. Lorsque vous partagez vos photos sur les r\u00e9seaux sociaux, on vous invite \u00e0 mentionner IBEW Canada en utilisant @ibewca sur Facebook et @IBEWCanada sur Twitter.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/gallery.mailchimp.com\/9110cbabd751bd3c9cea423d5\/images\/c8765594-171d-44d0-ac27-88a225bb7fa8.jpg\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La FIOE Canada s\u2019est jointe \u00e0 l\u2019Association canadienne de l\u2019\u00e9lectricit\u00e9 (AC\u00c9) le 2 octobre 2018 pour lancer une campagne nationale qui a pour but de r\u00e9clamer une loi f\u00e9d\u00e9rale pour d\u00e9signer le 10 juillet comme la Journ\u00e9e nationale de reconnaissance des monteurs de lignes. Le 10 juillet est une journ\u00e9e tr\u00e8s importante pour la FIOE;&#8230;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-1003804","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-uncategorized","7":"entry"},"translation":{"provider":"WPGlobus","version":"3.0.2","language":"fr","enabled_languages":["en","fr"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false}}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.ibewcanada.ca\/fr\/wp-json\/wp\/v2\/posts\/1003804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ibewcanada.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ibewcanada.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ibewcanada.ca\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ibewcanada.ca\/fr\/wp-json\/wp\/v2\/comments?post=1003804"}],"version-history":[{"count":0,"href":"https:\/\/www.ibewcanada.ca\/fr\/wp-json\/wp\/v2\/posts\/1003804\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.ibewcanada.ca\/fr\/wp-json\/wp\/v2\/media?parent=1003804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ibewcanada.ca\/fr\/wp-json\/wp\/v2\/categories?post=1003804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ibewcanada.ca\/fr\/wp-json\/wp\/v2\/tags?post=1003804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}